{"id":154895,"date":"2025-03-21T19:14:16","date_gmt":"2025-03-21T18:14:16","guid":{"rendered":"https:\/\/efecomunica.efe.com\/?p=154895"},"modified":"2025-03-21T19:14:16","modified_gmt":"2025-03-21T18:14:16","slug":"america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos","status":"publish","type":"post","link":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/","title":{"rendered":"Am\u00e9rica Latina aposta em alian\u00e7as e inova\u00e7\u00e3o tecnol\u00f3gica para preservar recursos h\u00eddricos"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u00a0A Am\u00e9rica Latina abriga quase um ter\u00e7o dos recursos h\u00eddricos do planeta, no entanto, essa \u00e1gua vital \u00e9 inacess\u00edvel para 166 milh\u00f5es de pessoas na regi\u00e3o, um problema que vem sendo combatido atrav\u00e9s de iniciativas que combinam a\u00e7\u00f5es colaborativas e inova\u00e7\u00e3o tecnol\u00f3gica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Diante desse cen\u00e1rio, surge o projeto &#8220;Aliados pela \u00c1gua&#8221;, uma convocat\u00f3ria emitida pela Coca-Cola que busca combater os problemas relacionados \u00e0 escassez de \u00e1gua.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para avan\u00e7ar na preserva\u00e7\u00e3o e no cuidado desse elemento essencial para a vida humana, existem &#8220;solu\u00e7\u00f5es inovadoras&#8221; agrupadas em projetos dedicados a enfrentar os desafios da escassez por meio da &#8220;otimiza\u00e7\u00e3o e do trabalho conjunto de especialistas de diferentes setores&#8221;, conforme destaca a informa\u00e7\u00e3o da rede de &#8220;Aliados pela \u00c1gua&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa convocat\u00f3ria surgiu no in\u00edcio de 2024 e conta com o apoio de organiza\u00e7\u00f5es como GETF e New Ventures para cumprir a miss\u00e3o de fortalecer a capacidade de organiza\u00e7\u00f5es sociais, comunit\u00e1rias e p\u00fablico-privadas que lideram projetos voltados \u00e0 conserva\u00e7\u00e3o e ao acesso sustent\u00e1vel a esse bem b\u00e1sico.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A nova gera\u00e7\u00e3o de &#8220;Aliados pela \u00c1gua&#8221; \u00e9 composta por seis projetos que realizar\u00e3o a\u00e7\u00f5es escal\u00e1veis que podem ser implementadas em diferentes regi\u00f5es com estresse h\u00eddrico. Al\u00e9m disso, essas iniciativas abordar\u00e3o &#8220;os problemas atuais e estabelecer\u00e3o as bases para uma gest\u00e3o mais eficiente da \u00e1gua no futuro&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No \u00e2mbito do Dia Mundial da \u00c1gua, comemorado todo dia 22 de mar\u00e7o, as Na\u00e7\u00f5es Unidas t\u00eam como objetivo central garantir o direito a esse recurso indispens\u00e1vel para todas as pessoas at\u00e9 2030, meta que est\u00e1 inclu\u00edda no ponto n\u00famero seis dos Objetivos de Desenvolvimento Sustent\u00e1vel (ODS).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora essa organiza\u00e7\u00e3o internacional esclare\u00e7a que cada regi\u00e3o enfrenta suas pr\u00f3prias dificuldades, na Am\u00e9rica Latina h\u00e1 pa\u00edses como o M\u00e9xico, onde especialistas da Universidade Aut\u00f4noma Metropolitana (UAM) j\u00e1 alertam para a possibilidade do Dia Zero em 2028, caso medidas urgentes n\u00e3o sejam tomadas, ou o Chile, que atualmente ocupa a primeira posi\u00e7\u00e3o em estresse h\u00eddrico na regi\u00e3o.<\/span><\/p>\n<h2><b>Infraestrutura eficiente e sustent\u00e1vel<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Por exemplo, no territ\u00f3rio mexicano, a sobreexplora\u00e7\u00e3o de aqu\u00edferos e as perdas de \u00e1gua nas redes de distribui\u00e7\u00e3o representam um desafio cr\u00edtico. Segundo a Comiss\u00e3o Nacional da \u00c1gua (CONAGUA), 33% dos munic\u00edpios n\u00e3o recebem \u00e1gua diariamente, e 32% da \u00e1gua \u00e9 desperdi\u00e7ada devido a vazamentos na infraestrutura.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para reduzir essas perdas, o projeto selecionado, FIDO Tech, desenvolveu tecnologias avan\u00e7adas para a detec\u00e7\u00e3o e reparo de vazamentos em sistemas p\u00fablicos e privados, otimizando a gest\u00e3o do recurso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Na lista de projetos apoiados pela Coca-Cola na Am\u00e9rica Latina, tamb\u00e9m est\u00e1 a Arable, uma plataforma que ajuda os agricultores a otimizar o uso da \u00e1gua em suas planta\u00e7\u00f5es, com presen\u00e7a em diversas bacias do M\u00e9xico. Esta \u00e9 uma a\u00e7\u00e3o chave, uma vez que, globalmente, 70% desse recurso b\u00e1sico \u00e9 consumido em atividades agr\u00edcolas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa batalha pela conserva\u00e7\u00e3o conta com a colabora\u00e7\u00e3o da ALIS, uma organiza\u00e7\u00e3o que trabalha com comunidades e empresas para promover pr\u00e1ticas agr\u00edcolas sustent\u00e1veis que reduzam o consumo de \u00e1gua com base na sua efici\u00eancia. A gest\u00e3o da ALIS foca principalmente em Baja Calif\u00f3rnia Sur, um dos estados mexicanos que enfrenta as secas mais severas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O mesmo problema ocorre no Chile, um pa\u00eds que est\u00e1 h\u00e1 14 anos enfrentando seca, o que reduziu os n\u00edveis de \u00e1gua nos reservat\u00f3rios e, consequentemente, afetou o abastecimento urbano e agr\u00edcola.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Portanto, a empresa Kilimo, outra das selecionadas na convocat\u00f3ria, implementou intelig\u00eancia artificial na gest\u00e3o de irriga\u00e7\u00e3o agr\u00edcola no Chile, M\u00e9xico e Argentina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ao &#8220;Aliados pela \u00c1gua&#8221; se somam outros dois projetos: Vbio, que busca promover a sociobioeconomia no Brasil, e Asa Alimentaria, que, al\u00e9m de buscar a sustentabilidade h\u00eddrica, visa criar um sistema alimentar equitativo em La Paz, capital do estado de Baja Calif\u00f3rnia Sur. EFE<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0A Am\u00e9rica Latina abriga quase um ter\u00e7o dos recursos h\u00eddricos do planeta, no entanto, essa \u00e1gua vital \u00e9 inacess\u00edvel para 166 milh\u00f5es de pessoas na regi\u00e3o, um problema que vem [&hellip;]<\/p>\n","protected":false},"author":198164093,"featured_media":154897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[125405,125402],"tags":[128160,127983,126416],"class_list":["post-154895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas-pt-pt","category-sustentabilidade","tag-agua-pt-pt","tag-coca-cola-pt-pt","tag-sustentabilidade"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Am\u00e9rica Latina aposta em alian\u00e7as e inova\u00e7\u00e3o tecnol\u00f3gica para preservar recursos h\u00eddricos - EFE Comunica<\/title>\n<meta name=\"description\" content=\"\u00a0A Am\u00e9rica Latina abriga quase um ter\u00e7o dos recursos h\u00eddricos do planeta, no entanto, essa \u00e1gua vital \u00e9 inacess\u00edvel para 166 milh\u00f5es de pessoas na regi\u00e3o,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Am\u00e9rica Latina aposta em alian\u00e7as e inova\u00e7\u00e3o tecnol\u00f3gica para preservar recursos h\u00eddricos - EFE Comunica","description":"\u00a0A Am\u00e9rica Latina abriga quase um ter\u00e7o dos recursos h\u00eddricos do planeta, no entanto, essa \u00e1gua vital \u00e9 inacess\u00edvel para 166 milh\u00f5es de pessoas na regi\u00e3o,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/#article","isPartOf":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/"},"author":{"name":"Ana Paula Raposo Chain","@id":"https:\/\/efecomunica.efe.com\/#\/schema\/person\/c909104001020699b704e3df33fef431"},"headline":"Am\u00e9rica Latina aposta em alian\u00e7as e inova\u00e7\u00e3o tecnol\u00f3gica para preservar recursos h\u00eddricos","datePublished":"2025-03-21T18:14:16+00:00","mainEntityOfPage":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/"},"wordCount":702,"publisher":{"@id":"https:\/\/efecomunica.efe.com\/#organization"},"image":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/#primaryimage"},"thumbnailUrl":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2025\/03\/rss-efe9149b6dd59a6a83559c7a3bef6af289740fbf894w-1536x1025-1.webp","keywords":["agua","Coca-Cola","sustentabilidade"],"articleSection":["Empresas","Sustentabilidade"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/","url":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/","name":"Am\u00e9rica Latina aposta em alian\u00e7as e inova\u00e7\u00e3o tecnol\u00f3gica para preservar recursos h\u00eddricos - EFE Comunica","isPartOf":{"@id":"https:\/\/efecomunica.efe.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/#primaryimage"},"image":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/#primaryimage"},"thumbnailUrl":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2025\/03\/rss-efe9149b6dd59a6a83559c7a3bef6af289740fbf894w-1536x1025-1.webp","datePublished":"2025-03-21T18:14:16+00:00","description":"\u00a0A Am\u00e9rica Latina abriga quase um ter\u00e7o dos recursos h\u00eddricos do planeta, no entanto, essa \u00e1gua vital \u00e9 inacess\u00edvel para 166 milh\u00f5es de pessoas na regi\u00e3o,","breadcrumb":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/#primaryimage","url":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2025\/03\/rss-efe9149b6dd59a6a83559c7a3bef6af289740fbf894w-1536x1025-1.webp","contentUrl":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2025\/03\/rss-efe9149b6dd59a6a83559c7a3bef6af289740fbf894w-1536x1025-1.webp","width":1536,"height":1025},{"@type":"BreadcrumbList","@id":"https:\/\/efecomunica.efe.com\/pt-pt\/america-latina-aposta-em-aliancas-e-inovacao-tecnologica-para-preservar-recursos-hidricos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/efecomunica.efe.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Am\u00e9rica Latina aposta em alian\u00e7as e inova\u00e7\u00e3o tecnol\u00f3gica para preservar recursos h\u00eddricos"}]},{"@type":"WebSite","@id":"https:\/\/efecomunica.efe.com\/#website","url":"https:\/\/efecomunica.efe.com\/","name":"EFE Comunica","description":"Contenidos para empresas","publisher":{"@id":"https:\/\/efecomunica.efe.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/efecomunica.efe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/efecomunica.efe.com\/#organization","name":"EFE Comunica","url":"https:\/\/efecomunica.efe.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/efecomunica.efe.com\/#\/schema\/logo\/image\/","url":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2020\/12\/Logo-EFE-Comunica_png.png","contentUrl":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2020\/12\/Logo-EFE-Comunica_png.png","width":1080,"height":486,"caption":"EFE Comunica"},"image":{"@id":"https:\/\/efecomunica.efe.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EFEComunicaAgenciaEFE","https:\/\/x.com\/EFEcomunica","https:\/\/www.linkedin.com\/showcase\/efecomunica"]},{"@type":"Person","@id":"https:\/\/efecomunica.efe.com\/#\/schema\/person\/c909104001020699b704e3df33fef431","name":"Ana Paula Raposo Chain","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdb673c87ee0b2e7929d64a955445cfbf4bfc5af80baee97082d08a440db678f?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdb673c87ee0b2e7929d64a955445cfbf4bfc5af80baee97082d08a440db678f?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdb673c87ee0b2e7929d64a955445cfbf4bfc5af80baee97082d08a440db678f?s=96&d=identicon&r=g","caption":"Ana Paula Raposo Chain"},"url":"https:\/\/efecomunica.efe.com\/pt-pt\/author\/achain\/"}]}},"jetpack_featured_media_url":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2025\/03\/rss-efe9149b6dd59a6a83559c7a3bef6af289740fbf894w-1536x1025-1.webp","jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcEg1r-Eij","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/posts\/154895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/users\/198164093"}],"replies":[{"embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=154895"}],"version-history":[{"count":2,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/posts\/154895\/revisions"}],"predecessor-version":[{"id":154898,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/posts\/154895\/revisions\/154898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/media\/154897"}],"wp:attachment":[{"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=154895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=154895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=154895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}