{"id":242419,"date":"2026-08-31T16:01:51","date_gmt":"2026-08-31T14:01:51","guid":{"rendered":"https:\/\/efecomunica.efe.com\/?p=242419"},"modified":"2026-09-01T19:53:42","modified_gmt":"2026-09-01T17:53:42","slug":"padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia","status":"publish","type":"post","link":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/","title":{"rendered":"Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina  foram demonstrados por meio de monitor inteligente de caixa de areia"},"content":{"rendered":"<p>(Informa\u00e7\u00e3o concedida pela entidade que a assina)<\/p>\n<p>Nova publica\u00e7\u00e3o demonstra como o monitoramento passivo em casa pode apoiar o reconhecimento mais precoce da doen\u00e7a renal cr\u00f4nica felina.<\/p>\n<p><strong>Purina Institute<\/strong> anuncia uma nova publica\u00e7\u00e3o que mostra que, ao <strong>monitorar o comportamento de elimina\u00e7\u00e3o de um gato em casa<\/strong>, \u00e9 poss\u00edvel identificar altera\u00e7\u00f5es sutis em como o pet faz suas necessidades que podem estar associadas \u00e0 doen\u00e7a renal cr\u00f4nica. Este estudo retrospectivo forneceu evid\u00eancias adicionais sobre as capacidades de um monitor inteligente de caixa de areia, para distinguir altera\u00e7\u00f5es significativas relacionadas \u00e0 doen\u00e7a renal cr\u00f4nica (DRC), juntamente com dados existentes sobre a frequ\u00eancia de defeca\u00e7\u00e3o em gatos1.<\/p>\n<p>As descobertas da <strong>Nestl\u00e9 Purina PetCare Global Research and Development<\/strong>, em conjunto com a The Ohio State University, publicadas em Animals, descrevem como um monitor inteligente de caixa de areia usa sensores e aprendizado autom\u00e1tico para acompanhar de forma cont\u00ednua e n\u00e3o invasiva os comportamentos de elimina\u00e7\u00e3o em casa \u2014 ajudando respons\u00e1veis de pets e equipes veterin\u00e1rias a reconhecer altera\u00e7\u00f5es mais cedo.<\/p>\n<p><strong>A DRC felina \u00e9 uma importante preocupa\u00e7\u00e3o de sa\u00fade<\/strong>, mas os sinais iniciais podem n\u00e3o ser identificados por m\u00e9todos tradicionais em consultas de rotina, que oferecem apenas avalia\u00e7\u00f5es pontuais. Em contraste, o monitoramento viabilizado por caixas de areia inteligentes pode criar uma vis\u00e3o di\u00e1ria da mic\u00e7\u00e3o, defeca\u00e7\u00e3o e peso corporal sem interromper a rotina do gato. O sistema descrito no artigo classifica eventos (como mic\u00e7\u00e3o, defeca\u00e7\u00e3o e visitas sem elimina\u00e7\u00e3o) e consegue diferenciar v\u00e1rios gatos no mesmo domic\u00edlio, compartilhando ent\u00e3o as tend\u00eancias por meio de um aplicativo conectado.<\/p>\n<h3>Destaques do estudo<\/h3>\n<ul>\n<li>An\u00e1lise retrospectiva dos dados do monitor inteligente de caixa de areia de 136 gatos, incluindo gatos com DRC diagnosticada e gatos sem condi\u00e7\u00f5es conhecidas.<\/li>\n<li>Os pesquisadores realizaram uma compara\u00e7\u00e3o entre grupos com DRC renal e grupos sem doen\u00e7a renal em aproximadamente duas d\u00fazias de caracter\u00edsticas mensur\u00e1veis pelo monitor, relacionadas \u00e0 frequ\u00eancia, ao peso e \u00e0 dura\u00e7\u00e3o dos eventos de elimina\u00e7\u00e3o, bem como \u00e0 entrada na caixa de areia e \u00e0 intensidade de escava\u00e7\u00e3o.<\/li>\n<li>Usando um subconjunto de gatos para o desenvolvimento do modelo e um subconjunto separado para valida\u00e7\u00e3o, a equipe construiu e avaliou uma abordagem preditiva destinada a sinalizar um perfil comportamental associado \u00e0 DRC.<\/li>\n<li>O monitor inteligente de caixa de areia conseguiu detectar esses comportamentos e identific\u00e1-los como indicativos de DRC.<\/li>\n<li>O estudo apoia o potencial do monitoramento passivo em casa para complementar o cuidado veterin\u00e1rio ao revelar padr\u00f5es que podem justificar exames de acompanhamento.<\/li>\n<\/ul>\n<p>&#8220;A doen\u00e7a renal cr\u00f4nica \u00e9 comum em gatos idosos, mas pode ser desafiador para os respons\u00e1veis pets reconhecerem seus sinais iniciais, j\u00e1 que as mudan\u00e7as podem ser graduais e f\u00e1ceis de passar despercebidas no dia a dia&#8221;, disse Ragen McGowan, PhD, da Nestl\u00e9 Purina PetCare Global Research &amp; Development. &#8220;Ao monitorar passivamente em casa o comportamento de elimina\u00e7\u00e3o e os padr\u00f5es de peso corporal, podemos identificar tend\u00eancias que podem sinalizar a necessidade de avalia\u00e7\u00e3o veterin\u00e1ria e testes diagn\u00f3sticos. Esse tipo de dado cont\u00ednuo e objetivo tem o potencial de complementar a rotina de cuidado e n\u00e3o substitu\u00ed-lo, ao incentivar os respons\u00e1veis a terem conversas mais precoces com seus m\u00e9dicos-veterin\u00e1rios e a fazerem acompanhamento quando o padr\u00e3o do gato mudar.&#8221;<\/p>\n<p>Para obter mais informa\u00e7\u00f5es sobre doen\u00e7a renal cr\u00f4nica, acesse <a href=\"http:\/\/www.purinainstitute.com\/pt-br\" rel=\"nofollow\">http:\/\/www.purinainstitute.com\/pt-br<\/a>.<\/p>\n<p>A Nestl\u00e9 Purina PetCare Global R&amp;D promove a ci\u00eancia da nutri\u00e7\u00e3o de pets por meio de pesquisa, inova\u00e7\u00e3o e colabora\u00e7\u00e3o para melhorar a sa\u00fade e o bem-estar dos pets em todo o mundo.<\/p>\n<h3>Observa\u00e7\u00e3o importante<\/h3>\n<p>O monitoramento por caixa de areia inteligente n\u00e3o \u00e9 uma ferramenta diagn\u00f3stica. Os autores enfatizam que alertas e mudan\u00e7as de tend\u00eancia nos dados devem ser interpretados no contexto e discutidos com um m\u00e9dico-veterin\u00e1rio, que pode recomendar testes confirmat\u00f3rios e avalia\u00e7\u00e3o cl\u00ednica.<\/p>\n<h3>Publica\u00e7\u00e3o<\/h3>\n<p>Langenfield-McCoy, N., Snow, L., Gordon, H., George, Z., Quimby, J., Arndt, O., Thomas, S., Schoeneck, N., &amp; McGowan, R. T. S. (2026). Enhancing detection of chronic kidney disease through smart litter box monitoring. Animals, 16(9), 1319. <a href=\"https:\/\/doi.org\/10.3390\/ani16091319\" rel=\"nofollow\">https:\/\/doi.org\/10.3390\/ani16091319<\/a><\/p>\n<p>Enhancing Detection of Feline Chronic Kidney Disease Through Smart Litter Box Monitoring<\/p>\n<h3>Refer\u00eancia<\/h3>\n<ul>\n<li>George, Z. M., Quimby, J. M., Jones, S., Brusach, K. B., &amp; Rudinsky, A. J. (2025). Quantification of defecation frequency in cats with and without chronic kidney disease. Journal of Feline Medicine and Surgery, 27(7). doi:10.1177\/1098612X251348011.<\/li>\n<\/ul>\n<h2>Sobre o Purina Institute<\/h2>\n<p>O Purina Institute dedica-se a transformar a ci\u00eancia da nutri\u00e7\u00e3o em informa\u00e7\u00f5es acion\u00e1veis que profissionais veterin\u00e1rios podem colocar em pr\u00e1tica em benef\u00edcio de seus pacientes. Por meio dos amplos recursos online, publica\u00e7\u00f5es e programas cient\u00edficos do Purina Institute, m\u00e9dicos-veterin\u00e1rios e membros da equipe podem se munir de informa\u00e7\u00f5es imparciais e baseadas em ci\u00eancia de que precisam para ajudar os pets a viverem vidas mais longas e melhores.<\/p>\n<p>View original content to download multimedia:<\/p>\n<p><a href=\"https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/padroes-da-eliminacao-associados-a-doenca-renal-felina--foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia-302865020.html\" target=\"_blank\" rel=\"noopener\">https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/padroes-da-eliminacao-associados-a-doenca-renal-felina&#8211;foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia-302865020.html<\/a><\/p>\n<p>FONTE Purina Institute<\/p>\n<p><em>AGENCIA EFE S.A.U.,S.M.E. n\u00e3o se responsabiliza pela informa\u00e7\u00e3o que cont\u00e9m esta mensagem e n\u00e3o assume nenhuma responsabilidade perante terceiros sobre o seu conte\u00fado total, estando igualmente desresponsabilizada da entidade autora do mesmo. Ag\u00eancia EFE reserva-se o direito de distribuir o comunicado de imprensa na linha de not\u00edcias ou de o publicar no EFE Comunica.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Informa\u00e7\u00e3o concedida pela entidade que a assina) Nova publica\u00e7\u00e3o demonstra como o monitoramento passivo em casa pode apoiar o reconhecimento mais precoce da doen\u00e7a renal cr\u00f4nica felina. Purina Institute anuncia [&hellip;]<\/p>\n","protected":false},"author":198164071,"featured_media":242420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[128468],"tags":[],"class_list":["post-242419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pr-newswire-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina foram demonstrados<\/title>\n<meta name=\"description\" content=\"Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina foram demonstrados por meio de monitor inteligente de caixa de areia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina foram demonstrados","description":"Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina foram demonstrados por meio de monitor inteligente de caixa de areia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/#article","isPartOf":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/"},"author":{"name":"EFE","@id":"https:\/\/efecomunica.efe.com\/#\/schema\/person\/38c335f1ce4cd42430576ef5499343b8"},"headline":"Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina foram demonstrados por meio de monitor inteligente de caixa de areia","datePublished":"2026-08-31T14:01:51+00:00","dateModified":"2026-09-01T17:53:42+00:00","mainEntityOfPage":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/"},"wordCount":968,"publisher":{"@id":"https:\/\/efecomunica.efe.com\/#organization"},"image":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/#primaryimage"},"thumbnailUrl":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2026\/08\/rss-efed07ca016be202e1094c4e96ce56d385e93a21acew.jpg","articleSection":["PR Newswire"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/","url":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/","name":"Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina foram demonstrados","isPartOf":{"@id":"https:\/\/efecomunica.efe.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/#primaryimage"},"image":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/#primaryimage"},"thumbnailUrl":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2026\/08\/rss-efed07ca016be202e1094c4e96ce56d385e93a21acew.jpg","datePublished":"2026-08-31T14:01:51+00:00","dateModified":"2026-09-01T17:53:42+00:00","description":"Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina foram demonstrados por meio de monitor inteligente de caixa de areia.","breadcrumb":{"@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/#primaryimage","url":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2026\/08\/rss-efed07ca016be202e1094c4e96ce56d385e93a21acew.jpg","contentUrl":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2026\/08\/rss-efed07ca016be202e1094c4e96ce56d385e93a21acew.jpg","width":1920,"height":1282},{"@type":"BreadcrumbList","@id":"https:\/\/efecomunica.efe.com\/pt-pt\/padroes-da-eliminacao-associados-a-doenca-renal-felina-foram-demonstrados-por-meio-de-monitor-inteligente-de-caixa-de-areia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/efecomunica.efe.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Padr\u00f5es da elimina\u00e7\u00e3o associados \u00e0 doen\u00e7a renal felina foram demonstrados por meio de monitor inteligente de caixa de areia"}]},{"@type":"WebSite","@id":"https:\/\/efecomunica.efe.com\/#website","url":"https:\/\/efecomunica.efe.com\/","name":"EFE Comunica","description":"Contenidos para empresas","publisher":{"@id":"https:\/\/efecomunica.efe.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/efecomunica.efe.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/efecomunica.efe.com\/#organization","name":"EFE Comunica","url":"https:\/\/efecomunica.efe.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/efecomunica.efe.com\/#\/schema\/logo\/image\/","url":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2020\/12\/Logo-EFE-Comunica_png.png","contentUrl":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2020\/12\/Logo-EFE-Comunica_png.png","width":1080,"height":486,"caption":"EFE Comunica"},"image":{"@id":"https:\/\/efecomunica.efe.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EFEComunicaAgenciaEFE","https:\/\/x.com\/EFEcomunica","https:\/\/www.linkedin.com\/showcase\/efecomunica"]},{"@type":"Person","@id":"https:\/\/efecomunica.efe.com\/#\/schema\/person\/38c335f1ce4cd42430576ef5499343b8","name":"EFE","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/e5fcf26bedbd04dc20896c519164a13fe69c6913f5830d7db51543fa04eb30b4?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5fcf26bedbd04dc20896c519164a13fe69c6913f5830d7db51543fa04eb30b4?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5fcf26bedbd04dc20896c519164a13fe69c6913f5830d7db51543fa04eb30b4?s=96&d=identicon&r=g","caption":"EFE"},"sameAs":["http:\/\/efe.com"],"url":"https:\/\/efecomunica.efe.com\/pt-pt\/author\/efedesarrollo\/"}]}},"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pcEg1r-113Z","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/efecomunica.efe.com\/wp-content\/uploads\/2026\/08\/rss-efed07ca016be202e1094c4e96ce56d385e93a21acew.jpg","_links":{"self":[{"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/posts\/242419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/users\/198164071"}],"replies":[{"embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=242419"}],"version-history":[{"count":7,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/posts\/242419\/revisions"}],"predecessor-version":[{"id":242674,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/posts\/242419\/revisions\/242674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/media\/242420"}],"wp:attachment":[{"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=242419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=242419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/efecomunica.efe.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=242419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}